{"id":172,"count":4,"description":"","link":"http:\/\/docetaste.com\/pt\/categoria-produto\/equipment\/","name":"Equipment","slug":"equipment","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/docetaste.com\/pt\/wp-json\/wp\/v2\/product_cat\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/docetaste.com\/pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"http:\/\/docetaste.com\/pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"http:\/\/docetaste.com\/pt\/wp-json\/wp\/v2\/product?product_cat=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}